{"id":2693,"date":"2015-11-20T11:37:34","date_gmt":"2015-11-20T10:37:34","guid":{"rendered":"http:\/\/herbal.es\/en\/?page_id=2693"},"modified":"2015-12-16T20:51:47","modified_gmt":"2015-12-16T19:51:47","slug":"curls-boucles","status":"publish","type":"page","link":"https:\/\/herbal.es\/en\/curls-boucles\/","title":{"rendered":"Curls and Boucles"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row margin_top=&#8221;0&#8243; margin_bottom=&#8221;0&#8243; full_width=&#8221;true&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221;][vc_column width=&#8221;1\/1&#8243; animation=&#8221;&#8221;][vc_single_image image=&#8221;2167&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;false&#8221; img_size=&#8221;full&#8221; el_class=&#8221;quitarimagen&#8221;][\/vc_column][\/vc_row][vc_row margin_top=&#8221;-90&#8243; margin_bottom=&#8221;50&#8243; full_width=&#8221;&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221; el_class=&#8221;titulocategoria&#8221; bg_type=&#8221;bg_color&#8221; bg_color_value=&#8221;#ffffff&#8221;][vc_column width=&#8221;1\/1&#8243; animation=&#8221;&#8221;][vc_column_text]<\/p>\n<h1 style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-450\" src=\"https:\/\/herbal.es\/wp-content\/uploads\/professional-care.png\" alt=\"professional-care\" width=\"320\" height=\"62\" \/><\/h1>\n<h1 style=\"text-align: center;\">Curly and wavy hair<\/h1>\n<p style=\"text-align: center;\">Restores the appeal of curly hair, controlling frizz and delivering perfectly defined, flexible and radiant waves. Strengthens and vitalizes the hair fibre, providing the optimum level of hydration to maintain the beauty of a shiny, smooth and healthy hair.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row margin_top=&#8221;0&#8243; margin_bottom=&#8221;0&#8243; full_width=&#8221;&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; animation=&#8221;&#8221; type=&#8221;&#8221; bg_color=&#8221;&#8221; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; bg_video_src_mp4=&#8221;&#8221; bg_video_src_ogv=&#8221;&#8221; bg_video_src_webm=&#8221;&#8221; bg_type=&#8221;&#8221; parallax_style=&#8221;&#8221; bg_image_new=&#8221;&#8221; layer_image=&#8221;&#8221; bg_image_repeat=&#8221;&#8221; bg_image_size=&#8221;&#8221; bg_cstm_size=&#8221;&#8221; bg_img_attach=&#8221;&#8221; parallax_sense=&#8221;&#8221; bg_image_posiiton=&#8221;&#8221; animation_direction=&#8221;&#8221; animation_repeat=&#8221;&#8221; video_url=&#8221;&#8221; video_url_2=&#8221;&#8221; u_video_url=&#8221;&#8221; video_opts=&#8221;&#8221; video_poster=&#8221;&#8221; u_start_time=&#8221;&#8221; u_stop_time=&#8221;&#8221; viewport_vdo=&#8221;&#8221; enable_controls=&#8221;&#8221; bg_override=&#8221;&#8221; disable_on_mobile_img_parallax=&#8221;&#8221; parallax_content=&#8221;&#8221; parallax_content_sense=&#8221;&#8221; fadeout_row=&#8221;&#8221; fadeout_start_effect=&#8221;&#8221; enable_overlay=&#8221;&#8221; overlay_color=&#8221;&#8221; overlay_pattern=&#8221;&#8221; overlay_pattern_opacity=&#8221;&#8221; overlay_pattern_size=&#8221;&#8221; overlay_pattern_attachment=&#8221;&#8221; multi_color_overlay=&#8221;&#8221; multi_color_overlay_opacity=&#8221;&#8221; seperator_enable=&#8221;&#8221; seperator_type=&#8221;&#8221; seperator_position=&#8221;&#8221; seperator_shape_size=&#8221;&#8221; seperator_svg_height=&#8221;&#8221; seperator_shape_background=&#8221;&#8221; seperator_shape_border=&#8221;&#8221; seperator_shape_border_color=&#8221;&#8221; seperator_shape_border_width=&#8221;&#8221; icon_type=&#8221;&#8221; icon=&#8221;&#8221; icon_size=&#8221;&#8221; icon_color=&#8221;&#8221; icon_style=&#8221;&#8221; icon_color_bg=&#8221;&#8221; icon_border_style=&#8221;&#8221; icon_color_border=&#8221;&#8221; icon_border_size=&#8221;&#8221; icon_border_radius=&#8221;&#8221; icon_border_spacing=&#8221;&#8221; icon_img=&#8221;&#8221; img_width=&#8221;&#8221; ult_hide_row=&#8221;&#8221; ult_hide_row_large_screen=&#8221;&#8221; ult_hide_row_desktop=&#8221;&#8221; ult_hide_row_tablet=&#8221;&#8221; ult_hide_row_tablet_small=&#8221;&#8221; ult_hide_row_mobile=&#8221;&#8221; ult_hide_row_mobile_large=&#8221;&#8221;][vc_column width=&#8221;1\/1&#8243; animation=&#8221;&#8221;]<div id=\"ult-carousel-18615118996a97f38852618\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"50\" data-rtl=\"false\" ><div class=\"ult-carousel-21122306546a97f388523da \" >[vc_row_inner el_id=&#8221;&#8221;][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;485&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;yes&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; img_size=&#8221;medium&#8221;][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3>SHAMPOO<\/h3>\n<h4>Moisturising shampoo perfect curls<\/h4>\n<p>With Grape Seed Extract and Silk Proteins, brings back the attractiveness of curly hair and controls frizz, achieving shiny, defined curls. Mild formula for everyday use.<\/p>\n<h4>Directions<\/h4>\n<p>Apply to damp hair, massage in and rinse. In case of contact with eyes, rinse immediately with plenty of water.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;]<div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><div class=\"smile_icon_list_wrap ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-barcode\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1292\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-1292 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Reference<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1292 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 16700 <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-expand\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1758\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-1758 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Format<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1758 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 750ml <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-leaf\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6560\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-6560 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Main ingredient<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6560 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Jojoba Oil <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7016\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-7016 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">0% clorants parabens<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7016 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information \u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/products-0\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7759\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-7759 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">100% natural extracts<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7759 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information\u00a0\u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/natural-philosophy-innovation\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><\/ul><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;&#8221;][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_single_image alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;yes&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; img_size=&#8221;medium&#8221; image=&#8221;487&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3>CONDITIONER &#038; MASK<\/h3>\n<h4>Perfect Curls<\/h4>\n<p>With Grape Seed Extract and Silk Proteins, brings back the attractiveness of curly or wavy hair and controls frizz, achieving shiny, defined curls. Conditions and untangles without weighing the hair down.<\/p>\n<h4>Directions<\/h4>\n<p>Apply after washing, massage in gently, leave to act for 1-3 minutes and rinse. In case of contact with eyes, rinse immediately with plenty of water. [\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;]<div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><div class=\"smile_icon_list_wrap ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-barcode\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5555\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-5555 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Reference<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5555 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 10650 <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-expand\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5768\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-5768 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Format<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5768 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 750ml <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-leaf\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9534\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-9534 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Main ingredient<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9534 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Jojoba Oil<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5856\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-5856 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">0% colorants parabens<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5856 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information \u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/products-0\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3906\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-3906 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">100% natural extracts<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3906 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information\u00a0\u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/natural-philosophy-innovation\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><\/ul><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner el_id=&#8221;&#8221;][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_single_image alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;yes&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; img_size=&#8221;medium&#8221; image=&#8221;488&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3>MASK<\/h3>\n<h4>Curly and wavy hair<\/h4>\n<p>With Grape Seed Extract and Silk Proteins, whose antioxidant and moisturising properties rejuvenate the hair. Its protective and emollient agents enhance the beauty of the curly or wavy hair, controlling frizz and achieving defined, flexible and shiny curls.<\/p>\n<h4>Directions<\/h4>\n<p>Apply after washing, massage in gently, leave to act for several minutes and rinse. In case of contact with eyes, rinse immediately with plenty of water.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/3&#8243;]<div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><div class=\"smile_icon_list_wrap ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list left circle with_bg\"><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-barcode\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3466\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-3466 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Reference<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3466 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 11700 <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-expand\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6668\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-6668 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Format<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6668 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p> 500ml <\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-leaf\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9367\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-9367 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Main ingredient<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9367 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>Jojoba Oil<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9713\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-9713 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">0% colorants parabens<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9713 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information \u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/products-0\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><div class=\"ult-item-wrap\" data-animation=\"animated fadeIn\"><li class=\"icon_list_item\" style=\" font-size:48px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:16px;border-width:1px;border-style:none;background:#007336;color:#ffffff;border-color:#333333;\"><i class=\"Defaults-check-square-o\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2973\" style=\"font-size:16px;\"><h3 class=\"ult-responsive\"  data-ultimate-target='#Info-list-wrap-2973 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">100% natural extracts<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2973 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><p>More information\u00a0\u00bb<\/p>\n<\/div><\/div><div class=\"icon_list_connector\"  style=\"border-color:#007336;\"><\/div><a href=\"\/en\/natural-philosophy-innovation\/\" class=\"ulimate-info-list-link\" ><\/a><\/li><\/div><\/ul><\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<\/div><\/div>            <script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function($){\r\n               \t\t$('.ult-carousel-21122306546a97f388523da').slick({dots: true,autoplaySpeed: 5000,speed: 600,infinite: true,arrows: true,nextArrow: '<button type=\"button\" style=\"color:#ffffff; font-size:32px;background:#007336;\" class=\"slick-next circle-bg\"><i class=\"ultsl-arrow-right4\"><\/i><\/button>',prevArrow: '<button type=\"button\" style=\"color:#ffffff; font-size:32px;background:#007336;\" class=\"slick-prev circle-bg\"><i class=\"ultsl-arrow-left4\"><\/i><\/button>',slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 769,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 481,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnHover: true,\r\n\t\t\t\t\t\tpauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style=\"color:#007336;\" class=\"ultsl-radio-unchecked\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n            [\/vc_column][\/vc_row][vc_row margin_top=&#8221;50&#8243; margin_bottom=&#8221;0&#8243; full_width=&#8221;&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221;][vc_column width=&#8221;1\/6&#8243; animation=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; animation=&#8221;&#8221;][vc_row_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/2&#8243;]<div class=\"ult-new-ib ult-ib-effect-style9 titulobanner  \"  style=\"\" data-opacity=\"1\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"\" src=\"https:\/\/herbal.es\/wp-content\/uploads\/banner-producto-cero1.jpg\"   \/><div id=\"interactive-banner-wrap-7444\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7444 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Products 0%<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-7444 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>Silicones free<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"\/en\/products-0\/\" ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column_inner][vc_column_inner el_class=&#8221;&#8221; width=&#8221;1\/2&#8243;]<div class=\"ult-new-ib ult-ib-effect-style9 titulobanner  \"  style=\"\" data-opacity=\"1\" data-hover-opacity=\"1\" ><img decoding=\"async\" class=\"ult-new-ib-img\" style=\"opacity:1;\" alt=\"\" src=\"https:\/\/herbal.es\/wp-content\/uploads\/banner-productos-naturales.jpg\"   \/><div id=\"interactive-banner-wrap-9238\" class=\"ult-new-ib-desc\" style=\"\"><h2 class=\"ult-new-ib-title ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-9238 .ult-new-ib-title'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\">Natural philosophy<\/h2><div class=\"ult-new-ib-content ult-responsive\"  data-ultimate-target='#interactive-banner-wrap-9238 .ult-new-ib-content'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"\"}'  style=\"font-weight:normal;\"><p>100% Respect to nature<\/p><\/div><\/div><a class=\"ult-new-ib-link\" href=\"\/en\/natural-philosophy-innovation\/\" ><\/a><\/div><script type=\"text\/javascript\">\r\n\t\t\t(function($){\r\n\t\t\t\t$(document).ready(function(){\r\n\t\t\t\t\t$(\".ult-new-ib\").css(\"opacity\",\"1\");\r\n\t\t\t\t});\r\n\t\t\t})(jQuery);\r\n\t\t\t<\/script>[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243; animation=&#8221;&#8221;][\/vc_column][\/vc_row][vc_row margin_top=&#8221;50&#8243; margin_bottom=&#8221;50&#8243; full_width=&#8221;&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221;][vc_column width=&#8221;1\/3&#8243; animation=&#8221;&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243; animation=&#8221;&#8221;][vc_column_text]<\/p>\n<h4>Explore whole collection of Professional Care:<\/h4>\n<p>[\/vc_column_text]<div class=\"ult-spacer spacer-6a97f3885342d\" data-id=\"6a97f3885342d\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div id=\"ult-carousel-5622044126a97f3885346d\" class=\"ult-carousel-wrapper  sliderpeque ult_horizontal\" data-gutter=\"15\" data-rtl=\"false\" ><div class=\"ult-carousel-9662277776a97f3885345e \" >[vc_single_image image=&#8221;221&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; title=&#8221;Gloss Intense&#8221; img_size=&#8221;large&#8221; link=&#8221;\/en\/gloss-intense-professional-care\/&#8221;][vc_single_image image=&#8221;203&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; title=&#8221;S.O.S. Total Repair&#8221; img_size=&#8221;large&#8221; link=&#8221;\/en\/s-o-s-total-repair\/&#8221;][vc_single_image image=&#8221;200&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; title=&#8221;Color Protect&#8221; img_size=&#8221;large&#8221; link=&#8221;\/en\/color-protect-professional-care\/&#8221;][vc_single_image image=&#8221;202&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;true&#8221; title=&#8221;Nutri Lisse Anti Frizz&#8221; img_size=&#8221;large&#8221; link=&#8221;\/en\/nutri-lisse-anti-frizz\/&#8221;]<\/div><\/div>            <script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function($){\r\n               \t\t$('.ult-carousel-9662277776a97f3885345e').slick({dots: true,autoplay: true,autoplaySpeed: 5000,speed: 300,infinite: true,arrows: false,slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 769,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 481,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnHover: true,\r\n\t\t\t\t\t\tpauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style=\"color:#333333;\" class=\"ultsl-radio-unchecked\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n            [\/vc_column][vc_column width=&#8221;1\/3&#8243; animation=&#8221;&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row margin_top=&#8221;0&#8243; margin_bottom=&#8221;0&#8243; full_width=&#8221;true&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221;][vc_column width=&#8221;1\/1&#8243; animation=&#8221;&#8221;][vc_single_image image=&#8221;2167&#8243; alignment=&#8221;center&#8221; border_color=&#8221;grey&#8221; img_link_large=&#8221;&#8221; img_link_target=&#8221;_self&#8221; image_hovers=&#8221;false&#8221; img_size=&#8221;full&#8221; el_class=&#8221;quitarimagen&#8221;][\/vc_column][\/vc_row][vc_row margin_top=&#8221;-90&#8243; margin_bottom=&#8221;50&#8243; full_width=&#8221;&#8221; padding_left=&#8221;0&#8243; padding_right=&#8221;0&#8243; bg_position=&#8221;top&#8221; bg_repeat=&#8221;no-repeat&#8221; bg_cover=&#8221;false&#8221; bg_attachment=&#8221;false&#8221; padding_top=&#8221;0&#8243; padding_bottom=&#8221;0&#8243; enable_parallax=&#8221;&#8221; parallax_speed=&#8221;0.1&#8243; video_opts=&#8221;&#8221; multi_color_overlay=&#8221;&#8221; el_class=&#8221;titulocategoria&#8221; bg_type=&#8221;bg_color&#8221; bg_color_value=&#8221;#ffffff&#8221;][vc_column width=&#8221;1\/1&#8243; animation=&#8221;&#8221;][vc_column_text] Curly and wavy hair Restores the appeal of curly&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2693","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/pages\/2693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/comments?post=2693"}],"version-history":[{"count":7,"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/pages\/2693\/revisions"}],"predecessor-version":[{"id":2897,"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/pages\/2693\/revisions\/2897"}],"wp:attachment":[{"href":"https:\/\/herbal.es\/en\/wp-json\/wp\/v2\/media?parent=2693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}